{"id":30701,"date":"2026-07-14T07:00:04","date_gmt":"2026-07-14T10:00:04","guid":{"rendered":"https:\/\/radiofobia.com.br\/podcast\/?p=30701"},"modified":"2026-07-10T16:26:44","modified_gmt":"2026-07-10T19:26:44","slug":"voz-off-107-monge-mauricio-dokei","status":"publish","type":"post","link":"https:\/\/radiofobia.com.br\/podcast\/2026\/07\/voz-off-107-monge-mauricio-dokei\/","title":{"rendered":"VOZ OFF 107 &#8211; Monge Mauricio Dokei"},"content":{"rendered":"<p><iframe title=\"VOZ 0FF 107 - Monge Mauricio Dokei\" src=\"https:\/\/omny.fm\/shows\/voz-off\/voz-0ff-107-monge-mauricio-dokei\/embed?media=audio&amp;size=wide&amp;style=cover\" width=\"100%\" height=\"180\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><em><strong>Sauda\u00e7\u00f5es, ouvintes apaixonados por locu\u00e7\u00e3o. Est\u00e1 NO AR o\u00a0<\/strong><\/em><em><strong>107\u00ba podcast VOZ OFF!<\/strong><\/em><\/p>\n<p>Neste epis\u00f3dio<span style=\"color: #666666;\">, <strong><a href=\"https:\/\/twitter.com\/antonioviviani\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/twitter.com\/antonioviviani&amp;source=gmail&amp;ust=1547142011247000&amp;usg=AFQjCNGZ8kg3VQj-BI_K7dDR21HNmPxEOA\">Ant\u00f4nio Viviani<\/a>\u00a0<\/strong>e\u00a0<strong><a href=\"https:\/\/twitter.com\/nicolalauletta\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/twitter.com\/nicolalauletta&amp;source=gmail&amp;ust=1547142011247000&amp;usg=AFQjCNEexDjV314C4BXxGZ5bnNDyXJ1YVg\">Nicola Lauletta<\/a> <\/strong><\/span>conversam com mais uma grande voz do r\u00e1dio.<\/p>\n<p>Nascido em S\u00e3o Paulo-SP, no Centro da cidade, nosso convidado depois mudou-se para o Itaim, em seguida para o Ibirapuera, locais onde teve uma inf\u00e2ncia feliz, daquelas de brincar na rua com amigos. Mas ele s\u00f3 come\u00e7ou a se interessar pelo r\u00e1dio, depois de ser por um tempo radioamador e por ter esse conhecimento, acabou sendo convidado a trabalhar na Bandeirantes e depois na Jovem Pan como r\u00e1dio escuta, municiando de informa\u00e7\u00f5es de momento aos programadores e jornalistas de plant\u00e3o nas r\u00e1dios.<\/p>\n<p>Tamb\u00e9m por convite, foi trabalhar como locutor nas R\u00e1dio Mulher e Morada do Sol em S\u00e3o Paulo e depois em Araraquara quando a emissora come\u00e7ou a transmitir ao vivo e onde fez muito sucesso.<\/p>\n<p>De Araraquara foi junto com seu colega de r\u00e1dio Irineu Toledo, trabalhar na Clube de Ribeir\u00e3o Preto como locutor, apresentador, operador e tudo o que fosse necess\u00e1rio na emissora e ainda ao mesmo tempo os dois trabalhavam na Intersom FM de S\u00e3o Carlos.<\/p>\n<p>A convite do saudoso Arnaldo Saccomani veio para S\u00e3o Paulo para ser coordenador da Antena 1, depois de um tempo foi para a R\u00e1dio Eldorado, em seguida para a Bandeirantes AM, fazer o programa Bandeirantes A Caminho do Sol nas madrugadas, depois \u00e0s tardes apresentando o Ciranda da Cidade. A pr\u00f3xima emissora foi a Transam\u00e9rica.<\/p>\n<p>Teve que se afastar para montar uma pequena rede de farm\u00e1cias, junto com a primeira esposa que era farmac\u00eautica, mas depois de um tempo, a convite do Irineu, foi fazer um hor\u00e1rio \u00e0 noite na Nova FM, atual Nova Brasil FM.<\/p>\n<p>Quem vai contar essa hist\u00f3ria de sucesso \u00e9 <strong>Mauricio Martins<\/strong>.<\/p>\n<p>A conversa aconteceu em <strong>junho de 2026<\/strong> e voc\u00ea vai ficar sabendo que por insist\u00eancia de uma namorada, foi conhecer um templo budista e come\u00e7ou a frequentar, assistir as palestras, participar das cerim\u00f4nias e acabou sendo convidado para se tornar um monge budista. Morou muitos anos no Jap\u00e3o, se formou monge, voltou ao Brasil e construiu um templo Budista onde est\u00e1 at\u00e9 hoje.<\/p>\n<p>Com a gente, e pra voc\u00eas, o <b>MONGE MAURICIO DOKEI!<\/b><\/p>\n<p><strong style=\"color: #990000;\">Para seguir nas redes sociais:<\/strong><br \/>\n&#8211; <a href=\"https:\/\/www.facebook.com\/podcastvozoff\/\" target=\"_blank\" rel=\"noopener noreferrer\">Curta a p\u00e1gina do podcast <strong>Voz Off<\/strong> no Facebook<\/a><br \/>\n&#8211; <a href=\"https:\/\/twitter.com\/podcastvozoff\" target=\"_blank\" rel=\"noopener noreferrer\">Siga o <strong>@podcastvozoff<\/strong> no Twitter<\/a><br \/>\n&#8211; <a href=\"https:\/\/www.facebook.com\/antoniovivianilocutor\/\" target=\"_blank\" rel=\"noopener noreferrer\">Curta a p\u00e1gina do <strong>Antonio Viviani<\/strong> no Facebook<\/a><br \/>\n&#8211; <a href=\"https:\/\/twitter.com\/antonioviviani\" target=\"_blank\" rel=\"noopener noreferrer\">Siga o <strong>@antonioviviani<\/strong> no Twitter<\/a><br \/>\n&#8211; <a href=\"https:\/\/www.instagram.com\/antonio.viviani\/\" target=\"_blank\" rel=\"noopener noreferrer\">Siga o <strong>@antonio.viviani<\/strong> no Instagram<\/a><br \/>\n&#8211; <a href=\"https:\/\/twitter.com\/nicolalauletta\" target=\"_blank\" rel=\"noopener noreferrer\">Siga o <strong>@nicolalauletta<\/strong> no Twitter<\/a><br \/>\n&#8211; <a href=\"https:\/\/www.facebook.com\/EchosStudios\" target=\"_blank\" rel=\"noopener noreferrer\">Curta a p\u00e1gina do <strong>Echo&#8217;s Studio<\/strong> no Facebook<\/a><br \/>\n&#8211; <a href=\"https:\/\/www.facebook.com\/vozaobra\/\" target=\"_blank\" rel=\"noopener noreferrer\">Curta a p\u00e1gina do <strong>Workshop de Locu\u00e7\u00e3o Voz A Obra<\/strong>\u00a0no Facebook<\/a><br \/>\n&#8211; <a href=\"http:\/\/leolop.es\/textosentido\" target=\"_blank\" rel=\"noopener noreferrer\">Ou\u00e7a tamb\u00e9m o podcast <strong>TEXTO SENTIDO<\/strong> com Ant\u00f4nio Viviani<\/a><\/p>\n<p><strong style=\"color: #990000;\">Assine o FEED do Voz Off:<\/strong><br \/>\nPara ouvir o Voz Off no seu agregador de podcasts preferido, <a href=\"http:\/\/leolop.es\/feedvozoff\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>clique aqui e assine o nosso FEED<\/strong><\/a>!<\/p>\n<p><strong style=\"color: #990000;\">Assine e avalie nosso podcast no iTunes:<\/strong><br \/>\nSe voc\u00ea usa o<strong> iTunes<\/strong> no seu computador, tablet ou smartphone, <a href=\"https:\/\/itunes.apple.com\/us\/podcast\/id1252595385\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>assine e avalie nosso podcast clicando aqui<\/strong><\/a>!<\/p>\n<p><strong style=\"color: #990000;\">Voz Off no Spotify:<\/strong><br \/>\nCaso prefira ouvir o <strong>Voz Off <\/strong>no<strong> Spotify<\/strong>, <a href=\"https:\/\/open.spotify.com\/show\/16gSvztELYfMu42Vu22gug?si=UW6_DO3bQwaYUt4aNjb4TQ\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>\u00e9 s\u00f3 clicar aqui e assinar o nosso podcast no servi\u00e7o de streaming<\/strong><\/a>!<\/p>\n<p><span style=\"color: #990000;\"><strong>E-mails:<\/strong><\/span><br \/>\nMande seu feedback pra gente atrav\u00e9s do e-mail\u00a0<a href=\"mailto:podcastvozoff@gmail.com\"><strong>podcastvozoff@gmail.com<\/strong><\/a>!<\/p>\n<p><span style=\"color: #990000;\"><strong>Publicidade:<\/strong><\/span><br \/>\n<a href=\"http:\/\/leolop.es\/rfcontato\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Entre em contato<\/strong><\/a> e saiba como <em>anunciar sua marca, produto ou servi\u00e7o em nossos podcasts<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ant\u00f4nio Viviani\u00a0e\u00a0Nicola Lauletta conversam com mais uma grande voz do r\u00e1dio: o Monge Mauricio Dokei!<\/p>\n","protected":false},"author":2,"featured_media":30702,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,1220],"tags":[],"class_list":["post-30701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast","category-vozoff"],"_links":{"self":[{"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/posts\/30701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/comments?post=30701"}],"version-history":[{"count":3,"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/posts\/30701\/revisions"}],"predecessor-version":[{"id":30705,"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/posts\/30701\/revisions\/30705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/media\/30702"}],"wp:attachment":[{"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/media?parent=30701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/categories?post=30701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiofobia.com.br\/podcast\/wp-json\/wp\/v2\/tags?post=30701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}